{"id":8141,"date":"2019-05-15T22:26:23","date_gmt":"2019-05-15T22:26:23","guid":{"rendered":"http:\/\/elsemanarioonl.wpengine.com\/?p=8141"},"modified":"2019-05-15T22:26:23","modified_gmt":"2019-05-15T22:26:23","slug":"metropolitan-state-university-de-denver-obtiene-el-estatus-hsi","status":"publish","type":"post","link":"https:\/\/www.elsemanarioonline.com\/es\/metropolitan-state-university-de-denver-obtiene-el-estatus-hsi\/","title":{"rendered":"Metropolitan State University de Denver Obtiene el Estatus HSI"},"content":{"rendered":"<p><!-- VideographyWP Plugin Message: Automatic video embedding prevented by plugin options. --><br \/>\n<strong>por Chanel Ward<\/strong><\/p>\n<p>\u00a0<\/p>\n<p>La Universidad Estatal Metropolitana de Denver ha sido conocida desde hace mucho tiempo por su diversidad y por ser la c\u00faspide de la educaci\u00f3n superior en la comunidad latina de Denver durante generaciones, y el 19 de febrero, la Universidad finalmente obtuvo su estatus de Instituci\u00f3n de Servicio a los Hispanos (Hispanic-Serving Institution, HSI).<\/p>\n<p>El umbral federal para calificar para una designaci\u00f3n HSI requiere que el 25% de todos los estudiantes se identifiquen como hispanos, mientras que tambi\u00e9n est\u00e1n inscritos a tiempo completo. Esa designaci\u00f3n se ha cumplido y superado con un 28,4%, es decir, m\u00e1s de 5.400 estudiantes, que cumplen este umbral.<\/p>\n<blockquote><p>\u00abHasta el \u00faltimo conteo, el 63.5% de los estudiantes blancos han llegado all\u00ed, pero para los estudiantes latinos esa cifra es del 28.6%, y en mi opini\u00f3n esa brecha es inaceptable\u00bb.<br \/>\nJanine Davidson, Presidente de MSU<\/p><\/blockquote>\n<p>El evento se celebr\u00f3 el 9 de mayo, donde una mezcla de estudiantes, ex-alumnos, activistas y la actual presidenta de la MSU, Janine Davidson, PhD y el ex-presidente, Dr. Stephen Jordan, PhD, anunciaron formalmente el esfuerzo de HIS.<\/p>\n<figure id=\"attachment_8138\" aria-describedby=\"caption-attachment-8138\" style=\"width: 432px\" class=\"wp-caption alignleft\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-8138 size-full\" src=\"https:\/\/i0.wp.com\/elsemanarioonl.wpengine.com\/wp-content\/uploads\/2019\/05\/CO-1-State-E-Colo-MSU-1pic-Davidson-and-Jordan.jpg?resize=432%2C648\" alt=\"\" width=\"432\" height=\"648\" srcset=\"https:\/\/i0.wp.com\/www.elsemanarioonline.com\/wp-content\/uploads\/2019\/05\/CO-1-State-E-Colo-MSU-1pic-Davidson-and-Jordan.jpg?w=432&ssl=1 432w, https:\/\/i0.wp.com\/www.elsemanarioonline.com\/wp-content\/uploads\/2019\/05\/CO-1-State-E-Colo-MSU-1pic-Davidson-and-Jordan.jpg?resize=100%2C150&ssl=1 100w, https:\/\/i0.wp.com\/www.elsemanarioonline.com\/wp-content\/uploads\/2019\/05\/CO-1-State-E-Colo-MSU-1pic-Davidson-and-Jordan.jpg?resize=200%2C300&ssl=1 200w\" sizes=\"(max-width: 432px) 100vw, 432px\" \/><figcaption id=\"caption-attachment-8138\" class=\"wp-caption-text\">Foto: Chanel Ward La presidenta de la Universidad Estatal Metropolitana de Denver, la Dra. Janine Davidson, y el ex presidente, el Dr. Stephen Jordan.<\/figcaption><\/figure>\n<p>El Dr. Jordan lanz\u00f3 la iniciativa HSI en 2007, cuando los estudiantes latinos representaban s\u00f3lo el 13% de lo que entonces era el Metropolitan State College.<\/p>\n<p>El Dr. Jordan, junto con Esther Rodr\u00edguez, ex asistente especial del presidente de HSI; Luis Torres, Ph.D., ex vicerrector; Judi D\u00edaz Bonacquisti, ex vicepresidenta asociada de Servicios de Inscripci\u00f3n; Angela M\u00e1rquez, Ph.D., asistente especial del presidente de HSI; el Equipo de Implementaci\u00f3n de HSI; y el Equipo de Trabajo de HSI fueron fundamentales en este esfuerzo.<\/p>\n<p>\u00abTuve la oportunidad de crear la visi\u00f3n y liderar el esfuerzo, pero este es un esfuerzo que fue organizado por mucha gente en este campus y en esta comunidad\u00bb, dijo el Dr. Jordan, sobre su papel en la designaci\u00f3n.<\/p>\n<p>\u00abEs realmente la gente de aqu\u00ed la que ha logrado ese objetivo\u00bb, dijo sobre el esfuerzo de m\u00e1s de diez a\u00f1os, al que aplaudi\u00f3 al Dr. Davidson por llevar la antorcha y crear el concepto Roadways.<\/p>\n<p>\u00abEl departamento ha establecido ampliamente una meta para asegurar que el 66% de la gente del estado tenga alg\u00fan tipo de credencial de educaci\u00f3n post-secundaria\u00bb, dijo el Dr. Davidson.<\/p>\n<p>\u00abHasta el \u00faltimo conteo, el 63.5% de los estudiantes blancos han llegado all\u00ed, pero para los estudiantes latinos esa cifra es del 28.6%, y en mi opini\u00f3n esa brecha es inaceptable\u00bb, afirm\u00f3.<\/p>\n<p>El Dr. Davidson habl\u00f3 con El Semanario para compartir lo que la designaci\u00f3n significa para la Universidad. \u00abEsto significa la acumulaci\u00f3n de diez a\u00f1os de esfuerzo por parte de un liderazgo incre\u00edblemente previsor que me precedi\u00f3 y que se dio cuenta de que esta poblaci\u00f3n es el futuro de Colorado y que MSU Denver necesitaba posicionarse de una manera que realmente pudiera servir a esa poblaci\u00f3n muy bien\u00bb, explic\u00f3 el Dr. Davidson.<\/p>\n<p>\u00abPero la otra cosa que creo que mucha gente no siempre se da cuenta es que al ser designados como HSI, significa que el 28% de nuestros estudiantes son latinos, pero el otro 72% no lo son; pero lo bueno de esto es que nos permite solicitar becas federales y dinero que ayudar\u00e1 a TODOS nuestros estudiantes\u00bb, agreg\u00f3 el Dr. Davidson, al tiempo que llam\u00f3 a la designaci\u00f3n, \u00abuna cosa excelente para la MSU y para todos nuestros estudiantes\u00bb.<\/p>\n<figure id=\"attachment_8140\" aria-describedby=\"caption-attachment-8140\" style=\"width: 864px\" class=\"wp-caption aligncenter\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"wp-image-8140 size-full\" src=\"https:\/\/i0.wp.com\/elsemanarioonl.wpengine.com\/wp-content\/uploads\/2019\/05\/CO-1-State-E-Colo-MSU-3pic.jpg?resize=640%2C427\" alt=\"\" width=\"640\" height=\"427\" srcset=\"https:\/\/i0.wp.com\/www.elsemanarioonline.com\/wp-content\/uploads\/2019\/05\/CO-1-State-E-Colo-MSU-3pic.jpg?w=864&ssl=1 864w, https:\/\/i0.wp.com\/www.elsemanarioonline.com\/wp-content\/uploads\/2019\/05\/CO-1-State-E-Colo-MSU-3pic.jpg?resize=600%2C400&ssl=1 600w, https:\/\/i0.wp.com\/www.elsemanarioonline.com\/wp-content\/uploads\/2019\/05\/CO-1-State-E-Colo-MSU-3pic.jpg?resize=150%2C100&ssl=1 150w, https:\/\/i0.wp.com\/www.elsemanarioonline.com\/wp-content\/uploads\/2019\/05\/CO-1-State-E-Colo-MSU-3pic.jpg?resize=300%2C200&ssl=1 300w, https:\/\/i0.wp.com\/www.elsemanarioonline.com\/wp-content\/uploads\/2019\/05\/CO-1-State-E-Colo-MSU-3pic.jpg?resize=90%2C60&ssl=1 90w, https:\/\/i0.wp.com\/www.elsemanarioonline.com\/wp-content\/uploads\/2019\/05\/CO-1-State-E-Colo-MSU-3pic.jpg?resize=180%2C120&ssl=1 180w, https:\/\/i0.wp.com\/www.elsemanarioonline.com\/wp-content\/uploads\/2019\/05\/CO-1-State-E-Colo-MSU-3pic.jpg?resize=95%2C64&ssl=1 95w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><figcaption id=\"caption-attachment-8140\" class=\"wp-caption-text\">Fotos: Chanel Ward Estudiantes en la Universidad Metropolitana del Estado de Denver, y profesores y partidarios de la comunidad recientemente celebr\u00f3 su estatus de Instituci\u00f3n de Servicios Hispanos (HSI). Arriba: estudiantes de MSU, Carlos Fresquez, MSU Professor, abajo: danzantes de Folklorico, y defensora de la comunidad Virginia Castro y Judi Diaz Bonacquisti, ex vicepresidente asociado de servicios de inscripci\u00f3n de MSU.<\/figcaption><\/figure>\n<p>Tambi\u00e9n reconoci\u00f3 las adversidades para los estudiantes en la continuaci\u00f3n de su educaci\u00f3n.<\/p>\n<p>\u00abUna de las cosas con las que se encuentran muchos de nuestros estudiantes latinos son los problemas con las transferencias, y los servicios de asesor\u00eda que se necesitan para realmente pasar por el sistema est\u00e1n ah\u00ed; y tambi\u00e9n lo est\u00e1n las becas que se pueden solicitar para realmente ayudar a la universidad a hacerlo mejor y eso ayudar\u00e1 a todos\u00bb.<\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" class=\"alignleft wp-image-8136 size-full\" src=\"https:\/\/i0.wp.com\/elsemanarioonl.wpengine.com\/wp-content\/uploads\/2019\/05\/CO-1-State-E-Colo-MSU-1graphic.jpg?resize=288%2C612\" alt=\"\" width=\"288\" height=\"612\" srcset=\"https:\/\/i0.wp.com\/www.elsemanarioonline.com\/wp-content\/uploads\/2019\/05\/CO-1-State-E-Colo-MSU-1graphic.jpg?w=288&ssl=1 288w, https:\/\/i0.wp.com\/www.elsemanarioonline.com\/wp-content\/uploads\/2019\/05\/CO-1-State-E-Colo-MSU-1graphic.jpg?resize=71%2C150&ssl=1 71w, https:\/\/i0.wp.com\/www.elsemanarioonline.com\/wp-content\/uploads\/2019\/05\/CO-1-State-E-Colo-MSU-1graphic.jpg?resize=141%2C300&ssl=1 141w\" sizes=\"(max-width: 288px) 100vw, 288px\" \/>La asistencia financiera ayudar\u00e1 a la retenci\u00f3n de estudiantes latinos, \u00abese es el prop\u00f3sito de las becas\u00bb, dijo el Dr. Davidson, al tiempo que agreg\u00f3 que, \u00abla asistencia del gobierno federal mejorar\u00e1 nuestra capacidad para hacer precisamente eso, en todos los aspectos\u00bb.<\/p>\n<p>El alcalde de Denver, Michael Hancock, elogi\u00f3 la iniciativa.<\/p>\n<p>\u00abSe trata de nivelar el campo de juego para la educaci\u00f3n y ayudar a todos nuestros estudiantes a alcanzar un futuro mejor\u201d.<\/p>\n<p>Para obtener m\u00e1s informaci\u00f3n sobre HSI de la MSU, visite su sitio web en <a href=\"https:\/\/red.msudenver.edu\/2019\/msu-denver-earns-hispanic-serving-institution-status.html\">msudenver.edu\/hsi. \u00a0<\/a><\/p>\n<p>\u00a0<\/p>\n<p>Chanel Ward es un Reportero Independiente de The Weekly Issue\/El Semanario. Traducci\u00f3n por Juan Carlos Uribe-The Weekly Issue\/El Semanario.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Para Noticias de Colorado: <\/strong><a href=\"http:\/\/www.ELSEMANARIOCOLORADO.COM\"><strong>ELSEMANARIOCOLORADO.COM<\/strong><\/a><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>por Chanel Ward \u00a0 La Universidad Estatal Metropolitana de Denver ha sido conocida desde hace mucho tiempo por su diversidad y por ser la c\u00faspide de la educaci\u00f3n superior en&#8230;<\/p>\n","protected":false},"author":403,"featured_media":8142,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[71],"tags":[],"class_list":["post-8141","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estado"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.elsemanarioonline.com\/wp-content\/uploads\/2019\/05\/CO-1-State-S-Colo-MSU-2pic.jpg?fit=432%2C431&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.elsemanarioonline.com\/es\/wp-json\/wp\/v2\/posts\/8141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elsemanarioonline.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elsemanarioonline.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elsemanarioonline.com\/es\/wp-json\/wp\/v2\/users\/403"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elsemanarioonline.com\/es\/wp-json\/wp\/v2\/comments?post=8141"}],"version-history":[{"count":0,"href":"https:\/\/www.elsemanarioonline.com\/es\/wp-json\/wp\/v2\/posts\/8141\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elsemanarioonline.com\/es\/wp-json\/wp\/v2\/media\/8142"}],"wp:attachment":[{"href":"https:\/\/www.elsemanarioonline.com\/es\/wp-json\/wp\/v2\/media?parent=8141"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elsemanarioonline.com\/es\/wp-json\/wp\/v2\/categories?post=8141"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elsemanarioonline.com\/es\/wp-json\/wp\/v2\/tags?post=8141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}