{"id":23159,"date":"2024-01-04T16:14:20","date_gmt":"2024-01-04T16:14:20","guid":{"rendered":"https:\/\/www.elsemanarioonline.com\/?p=23159"},"modified":"2024-01-04T16:14:20","modified_gmt":"2024-01-04T16:14:20","slug":"certificados-y-titulos-post-secundarios-ofrecen-buen-retorno-de-la-inversion","status":"publish","type":"post","link":"https:\/\/www.elsemanarioonline.com\/es\/certificados-y-titulos-post-secundarios-ofrecen-buen-retorno-de-la-inversion\/","title":{"rendered":"Certificados y T\u00edtulos Post-Secundarios Ofrecen Buen Retorno de la Inversi\u00f3n"},"content":{"rendered":"<p><!-- VideographyWP Plugin Message: Automatic video embedding prevented by plugin options. --><br \/>\n\u00a0<\/p>\n<p><strong>Por Eric Galatas<\/strong><\/p>\n<p>\u00a0<\/p>\n<p>Los habitantes de Colorado que se grad\u00faan de la universidad o de las escuelas vocacionales est\u00e1n listos para unirse al mercado laboral equipados con habilidades altamente competitivas y de gran demanda necesarias para prosperar en la carrera profesional elegida, seg\u00fan el <a href=\"https:\/\/cdhe.colorado.gov\/data-and-research\/research\/education-workforce\/ReturnOnInvestment\">\u00faltimo informe<\/a> de retorno de la inversi\u00f3n del Departamento de Educaci\u00f3n Superior de Colorado. La Dra. Angie Paccione dirige la agencia y a\u00f1ade que hay importantes beneficios al obtener cualquier educaci\u00f3n o capacitaci\u00f3n m\u00e1s all\u00e1 de la escuela secundaria.<\/p>\n<p>\u00a0<\/p>\n<p>\u00abCuando se obtiene una educaci\u00f3n superior, se obtienen mayores ingresos y mejores resultados de salud. Obtienes menos desempleo. Normalmente, la deuda disminuye,\u00bb agreg\u00f3 tambi\u00e9n Paccione.<\/p>\n<p>\u00a0<\/p>\n<p>Nueve de cada diez empleadores en el estado dicen que tienen puestos de trabajo que cubrir, pero no pueden encontrar trabajadores calificados. Colorado ocupa el segundo lugar a nivel nacional con m\u00e1s del 60% de sus residentes con alg\u00fan nivel de educaci\u00f3n postsecundaria, incluido un gran n\u00famero de personas que se mudan al estado con un t\u00edtulo en mano.<\/p>\n<p>\u00a0<\/p>\n<p>Paccione destaca el \u00e9xito de <a href=\"https:\/\/cdhe.colorado.gov\/about-us\/divisions\/cosi-colorado-opportunity-scholarship-initiative\">la Inciativa de Becas de Oportunidad de Colorado<\/a>, que ha demostrado que es posible cerrar esa brecha de logros. Pero ella explica que se necesita m\u00e1s financiaci\u00f3n para ampliar y llegar a m\u00e1s estudiantes.<\/p>\n<p>\u00a0<\/p>\n<p>\u00abFue dise\u00f1ado para que estudiantes de bajos ingresos, primera generaci\u00f3n y de color obtengan becas y servicios de apoyo integrales. Estos estudiantes cambiar\u00e1n las trayectorias de sus familias y, por supuesto, de ellos mismos,\u00bb indic\u00f3 adem\u00e1s Paccione.<\/p>\n<p>\u00a0<\/p>\n<p>Cada nuevo graduado postsecundario en Colorado aporta m\u00e1s de $132.000 al PIB del estado. Los trabajadores de Colorado sin t\u00edtulo o credencial ganan en promedio menos de $1.000 por semana, en comparaci\u00f3n con $1.500 por semana para aquellos con t\u00edtulos de licenciatura y m\u00e1s de $2.000 por semana para aquellos con t\u00edtulos avanzados. Paccione asegura que el estado ha tomado medidas para eliminar el costo como barrera.<\/p>\n<p>\u00a0<\/p>\n<p>\u00abTenemos alrededor de 12 ocupaciones que los estudiantes en Colorado pueden realizar sin costo alguno de matr\u00edcula ni cuotas, enfatiz\u00f3 la entrevistada. Los oficios de la construcci\u00f3n, extinci\u00f3n de incendios o bomberos, educaci\u00f3n primaria e infantil, gesti\u00f3n forestal y auxiliares de enfermer\u00eda titulados.\u00bb<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>Eric Galatas es productor de <a href=\"https:\/\/www.publicnewsservice.org\/\">Public News Service.<\/a><\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 Por Eric Galatas \u00a0 Los habitantes de Colorado que se grad\u00faan de la universidad o de las escuelas vocacionales est\u00e1n listos para unirse al mercado laboral equipados con habilidades&#8230;<\/p>\n","protected":false},"author":1,"featured_media":23160,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[71],"tags":[],"class_list":["post-23159","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estado"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.elsemanarioonline.com\/wp-content\/uploads\/2024\/01\/CO-2-State-E-Colo-Higher-Education-1pic-by-AdobeStock_567112081-copy-1.jpg?fit=720%2C480&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.elsemanarioonline.com\/es\/wp-json\/wp\/v2\/posts\/23159","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elsemanarioonline.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elsemanarioonline.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elsemanarioonline.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elsemanarioonline.com\/es\/wp-json\/wp\/v2\/comments?post=23159"}],"version-history":[{"count":0,"href":"https:\/\/www.elsemanarioonline.com\/es\/wp-json\/wp\/v2\/posts\/23159\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elsemanarioonline.com\/es\/wp-json\/wp\/v2\/media\/23160"}],"wp:attachment":[{"href":"https:\/\/www.elsemanarioonline.com\/es\/wp-json\/wp\/v2\/media?parent=23159"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elsemanarioonline.com\/es\/wp-json\/wp\/v2\/categories?post=23159"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elsemanarioonline.com\/es\/wp-json\/wp\/v2\/tags?post=23159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}