{"id":13653,"date":"2021-03-11T21:07:18","date_gmt":"2021-03-11T21:07:18","guid":{"rendered":"http:\/\/elsemanariocalifornia.com\/?p=10029"},"modified":"2021-03-11T21:07:18","modified_gmt":"2021-03-11T21:07:18","slug":"las-promotoras-llevan-dosis-de-esperanza-a-las-comunidades-2","status":"publish","type":"post","link":"https:\/\/www.elsemanarioonline.com\/es\/las-promotoras-llevan-dosis-de-esperanza-a-las-comunidades-2\/","title":{"rendered":"Las Promotoras Llevan \u2018Dosis de Esperanza\u2019 a las Comunidades"},"content":{"rendered":"<p><!-- VideographyWP Plugin Message: Automatic video embedding prevented by plugin options. --><br \/>\n<strong>Por Mark Hedin<\/strong><\/p>\n<p>\u00a0<\/p>\n<p>El Condado de Los \u00c1ngeles est\u00e1 trabajando para cerrar las brechas de equidad en la distribuci\u00f3n de la vacuna contra la COVID-19 en las comunidades muy afectadas, confiando en trabajadores sanitarios de la comunidad conocidos como promotoras, nuevas cl\u00ednicas de vacunaci\u00f3n m\u00f3viles, y sitios de vacunaci\u00f3n gestionados por una red de organizaciones comunitarias, entre otras medidas.<\/p>\n<p>\u201cHay esperanza a la vista\u201d, dijo Hilda L. Solis, presidenta del Consejo de Representantes, en el informe televisado patrocinado por el condado el d\u00eda 4 de marzo, se\u00f1alando una constante disminuci\u00f3n en los casos, hospitalizaciones y muertes de la COVID-19.<\/p>\n<p>Pero mientras que m\u00e1s de 2.2 millones de personas han recibido por lo menos una dosis de la vacuna, \u201ctenemos mucho trabajo por hacer para asegurar que los m\u00e1s vulnerables en nuestras comunidades est\u00e9n recibiendo sus dosis de esperanza\u201d, insisti\u00f3 Solis.<\/p>\n<p>\u201cEn las ciudades del Este de LA en mi distrito, donde las tasas de infecci\u00f3n ascienden al 20%, solo el 11.4% de los residentes se ha vacunado \u2013 mientras que en Bel Air, los residentes elegibles que se han vacunado representan el 34.3%. Esta es una de las tasas de vacunaci\u00f3n m\u00e1s bajas en nuestro condado, aqu\u00ed mismo\u201d.<\/p>\n<p>Aunque las comunidades afroamericanas y latinas tienen tasas de infecciones y muertes m\u00e1s altas en la pandemia, sus tasas de vacunaci\u00f3n \u201csiguen peligrosamente bajas\u201d \u2013 al 28.9% y 34.3% respectivamente \u2013 \u201cconsiderablemente m\u00e1s bajas que las de sus hom\u00f3logos blancos y asi\u00e1tico-americanos\u201d, observ\u00f3 Solis.<\/p>\n<p>Entre sus respuestas, el condado ha invertido $30 millones en las \u201cpromotoras\u201d, una iniciativa de trabajadores sanitarios de la comunidad, para ayudar y animar a la gente a que se vacune cuando sea elegible hacerlo y seg\u00fan permita el suministro.<\/p>\n<p>\u201cEs una red de vecinos, gente que conocemos y en quien confiamos, que vive en nuestras comunidades\u201d, dijo Solis de los m\u00e1s de 900 trabajadores a tiempo completo o parcial.<br \/>\n\u201cSe organizan en centros comunitarios, en lugares religiosos e incluso reuni\u00e9ndose con gente en las lavander\u00edas. Su misi\u00f3n es conectar a la gente con la informaci\u00f3n y recursos correctos \u2026 para generar esa confianza entre el gobierno, el Condado de LA, nuestros servicios y gente real\u201d.<\/p>\n<p>Hasta el momento, las promotoras han ayudado a m\u00e1s de 200,000 residentes del condado, proporcionando equipo de protecci\u00f3n personal y conexiones a otros recursos mediante una red de 16 organizaciones comunitarias dirigidas por el Centro de Mujeres del Este de Los \u00c1ngeles.<\/p>\n<p>Una, con el St. John\u2019s Well Child and Family Center, produjo un nuevo sitio de vacunaci\u00f3n en el Centro c\u00edvico del Este de L.A. que puede vacunar a entre 400 y 600 personas por d\u00eda, de martes a domingos, dijo.<\/p>\n<figure id=\"attachment_10028\" aria-describedby=\"caption-attachment-10028\" style=\"width: 576px\" class=\"wp-caption aligncenter\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-10028 size-full\" src=\"https:\/\/i0.wp.com\/elsemanariocalifornia.com\/wp-content\/uploads\/2021\/03\/CA-1-State-E-Calif-Promotoras-1pic-by-via-Ethnic-Media-Services.jpg?resize=576%2C421&ssl=1\" alt=\"\" width=\"576\" height=\"421\" \/><figcaption id=\"caption-attachment-10028\" class=\"wp-caption-text\">Foto: East Los Angeles Women\u2019s Center El Condado de Los \u00c1ngeles est\u00e1 trabajando para cerrar las brechas de equidad en la distribuci\u00f3n de la vacuna contra la COVID-19 en las comunidades muy afectadas, confiando en trabajadores sanitarios de la comunidad conocidos como promotoras<\/figcaption><\/figure>\n<p>Solis tambi\u00e9n describi\u00f3 una nueva cl\u00ednica m\u00f3vil de vacunaci\u00f3n que lleva vacunas a la gente mayor en la vivienda p\u00fablica y que no ha podido programar citas debido a la falta de Internet o a veces de acceso a tel\u00e9fono.<\/p>\n<p>\u201cVamos a asegurarnos de que esas dosis vayan a la gente correcta y de que informemos a nuestras comunidades acerca de esta asociaci\u00f3n\u201d, dijo Solis. \u201cSolo trabajando juntos vamos a derrotar a esta pandemia\u201d.<\/p>\n<p>La dra. Barbara Ferrer, directora de salud p\u00fablica del condado, tambi\u00e9n celebr\u00f3 la disminuci\u00f3n desde enero de la tasa de nuevos casos, hospitalizaciones y muertes de la COVID-19, pero advirti\u00f3 de que la disminuci\u00f3n solo baj\u00f3 los n\u00fameros de la pandemia a d\u00f3nde estaban antes de la pronunciada ola que empez\u00f3 en noviembre.<\/p>\n<blockquote><p>\u201cVamos a asegurarnos de que esas dosis vayan a la gente correcta y de que informemos a nuestras comunidades acerca de esta asociaci\u00f3n. Solo trabajando juntos vamos a derrotar a esta pandemia\u201d.<br \/>\nHilda L. Solis, Consejo de Representantes de LA\n<\/p><\/blockquote>\n<p>Algunos d\u00edas de este a\u00f1o, dijo, ha tenido que informar de m\u00e1s de 100 muertes relacionadas con la COVID, mientras que a principios de noviembre la media era de 14.<\/p>\n<p>\u201cEsta pandemia est\u00e1 lejos de haber terminado\u201d, dijo. Sin embargo, si el n\u00famero de casos sigue disminuyendo, en unas semanas el condado podr\u00eda ser declarado de \u201cnivel rojo\u201d, lo que permitir\u00eda m\u00e1s reaperturas.<\/p>\n<p>\u201cComo puede que las familias est\u00e9n ahora haciendo planes para las vacaciones de primavera\u201d, dijo, \u201cpor favor consideren quedarse en su localidad y gozar de los preciosos espacios al aire libre alrededor de nuestro condado: parques, playas y senderos. Debemos seguir evitando viajes y reuniones, sobre todo aquellas que transcurren en interiores\u201d.<\/p>\n<p>Las citas y vacunaciones se proporcionan sin costo y bajo las reglas de absoluta confidencialidad t\u00edpicas de todos los historiales m\u00e9dicos, a\u00f1adi\u00f3 Ferrer. Las vacunas se ofrecen sin que se haga ninguna pregunta acerca de la nacionalidad, residencia permanente legal (o \u201ctarjeta verde\u201d), o situaci\u00f3n migratoria de la persona, y no hay requisitos de documentos de gobierno de ning\u00fan tipo.<\/p>\n<p>\u201cPor favor, no dejen que su situaci\u00f3n migratoria les impida a vacunarse\u201d, dijo. \u201cNo necesitan una identificaci\u00f3n del gobierno.\u201d<\/p>\n<p>Los \u00c1ngeles tiene ahora m\u00e1s de 500 sitios de vacunaci\u00f3n en todo el condado, en docenas de hospitales, centenares de farmacias, y otros sitios abiertos para quienes re\u00fanan los requisitos para una vacuna.<\/p>\n<p>\u201cTodav\u00eda no tenemos suficientes dosis para todos los que re\u00fanen los requisitos\u201d, dijo Ferrer, pero el condado est\u00e1 aumentando sus unidades de vacunaci\u00f3n m\u00f3viles, expandiendo la capacidad de la central telef\u00f3nica y, recientemente, reserv\u00f3 2,000 citas para organizaciones comunitarias para programar a clientes que no pueden program\u00e1rselas solos.<\/p>\n<p>Ferrer estaba entusiasmada con la nueva vacuna de Johnson & Johnson, y dijo que de ninguna manera es inferior a las opciones de Pfizer y Moderna, aunque solo requiera una dosis y sea m\u00e1s f\u00e1cil de almacenar.<\/p>\n<p>La \u00faltima ponente del informe televisado fue Jazmin Flores, principal promotora del Centro de mujeres del Este de Los \u00c1ngeles, cuyo trabajo incluye visitas a supermercados, gasolineras, y otros negocios locales para colgar folletos y divulgar la informaci\u00f3n en las comunidades de las personas que carecen de vivienda.<\/p>\n<p>\u201cPodemos entender a nuestra comunidad\u201d, dijo al describir a un hombre que dorm\u00eda en su coche porque hab\u00eda dado positivo por COVID y ten\u00eda miedo de contagiar a su familia. Como promotora, ella pudo buscarle un albergue.<\/p>\n<p>Vea un <a href=\"https:\/\/www.youtube.com\/watch?v=Kzkob6cg1so&t=7s\">video <\/a>de los promotoras de East Los Angeles Women\u2019s Center<\/p>\n<p>\u00a0<\/p>\n<p>Mark Hedin es un reportero de <a href=\"https:\/\/ethnicmediaservices.org\/\">Ethnic Media Services.<\/a>\u00a0Traducci\u00f3n por Ethnic Media Services.<\/p>\n<p>\u00a0<\/p>\n<p><strong>Para M\u00e1s Noticias de California: <\/strong><a href=\"http:\/\/WWW.ELSEMANARIO.US\"><strong>ELSEMANARIO.US<\/strong><\/a><\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Mark Hedin \u00a0 El Condado de Los \u00c1ngeles est\u00e1 trabajando para cerrar las brechas de equidad en la distribuci\u00f3n de la vacuna contra la COVID-19 en las comunidades muy&#8230;<\/p>\n","protected":false},"author":403,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[100],"tags":[],"class_list":["post-13653","post","type-post","status-publish","format-standard","hentry","category-california-es"],"jetpack_featured_media_url":"","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.elsemanarioonline.com\/es\/wp-json\/wp\/v2\/posts\/13653","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elsemanarioonline.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elsemanarioonline.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elsemanarioonline.com\/es\/wp-json\/wp\/v2\/users\/403"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elsemanarioonline.com\/es\/wp-json\/wp\/v2\/comments?post=13653"}],"version-history":[{"count":0,"href":"https:\/\/www.elsemanarioonline.com\/es\/wp-json\/wp\/v2\/posts\/13653\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.elsemanarioonline.com\/es\/wp-json\/wp\/v2\/media?parent=13653"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elsemanarioonline.com\/es\/wp-json\/wp\/v2\/categories?post=13653"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elsemanarioonline.com\/es\/wp-json\/wp\/v2\/tags?post=13653"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}